{"id":3244,"date":"2024-04-11T12:15:42","date_gmt":"2024-04-11T10:15:42","guid":{"rendered":"https:\/\/www.landesbasketball.org\/?p=3244"},"modified":"2024-04-11T12:15:42","modified_gmt":"2024-04-11T10:15:42","slug":"departementale-1-laforet-saint-sever-phase-2-journee-7","status":"publish","type":"post","link":"https:\/\/www.comite40.lebasket.net\/index.php\/2024\/04\/11\/departementale-1-laforet-saint-sever-phase-2-journee-7\/","title":{"rendered":"DEPARTEMENTALE 1 LAFORET SAINT-SEVER \u2013 PHASE 2 JOURNEE 7"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"http:\/\/www.comite40.lebasket.net\/wp-content\/uploads\/2024\/04\/D1UJSBP-1024x1024.jpg\" alt=\"\" class=\"wp-image-3245\" srcset=\"https:\/\/www.comite40.lebasket.net\/wp-content\/uploads\/2024\/04\/D1UJSBP-1024x1024.jpg 1024w, https:\/\/www.comite40.lebasket.net\/wp-content\/uploads\/2024\/04\/D1UJSBP-300x300.jpg 300w, https:\/\/www.comite40.lebasket.net\/wp-content\/uploads\/2024\/04\/D1UJSBP-150x150.jpg 150w, https:\/\/www.comite40.lebasket.net\/wp-content\/uploads\/2024\/04\/D1UJSBP-768x768.jpg 768w, https:\/\/www.comite40.lebasket.net\/wp-content\/uploads\/2024\/04\/D1UJSBP.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption>L&rsquo;\u00e9quipe 2 masculine d&rsquo;UJSBP<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>DEPARTEMENTALE MASCULINE 1<\/em><\/strong>&nbsp;<strong><em>\u2013 D1 LAFORET SAINT-SEVER<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>POULE HAUTE \u2013 PLAY-OFF<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>ST CRICQ 2 &#8211; COTEAUX DU LUY 3 : <\/strong>ST CRICQ 2 a pris une nette revanche face \u00e0 B.L.A.C 2 gr\u00e2ce en particulier \u00e0 un efficace deuxi\u00e8me quart temps (31\/15) et s\u2019\u00e9tait nettement impos\u00e9 lors de la rencontre aller face \u00e0 COTEAUX DU LUY 3. Ils devraient donc r\u00e9cidiver d\u2019autant qu\u2019ils peuvent encore pr\u00e9tendre \u00e0 une place en finale. Ce ne sera peut \u00eatre pas si \u00e9vident car leurs visiteurs ont repris go\u00fbt \u00e0 la victoire avec la mani\u00e8re en ne laissant aucune chance \u00e0 C.B.P.L.\u00a0\u00a0<strong>\u00a0\u00a0\u00a0<\/strong>\u00a0\u00a0\u00a0\u00a0<strong>\u00a0\u00a0<\/strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>CSA 2 &#8211; ASCH 3 :\u00a0<\/strong>Dans une rencontre d\u00e9fensive, C.S.A 2 n\u2019a pu inqui\u00e9ter les leaders, alors qu\u2019A.S.C.H 3 avec un effectif amoindri s\u2019est nettement inclin\u00e9 lors de la r\u00e9ception de B.T.O. L\u2019enjeu de cette rencontre sera donc relatif, ces deux \u00e9quipes ne pouvant plus pr\u00e9tendre \u00e0 une place en finale. C.S.A 2 qui avait \u00e9chou\u00e9 de peu lors de la confrontation aller sera sans doute d\u00e9sireux de prendre une revanche\u00a0; revanche possible s\u2019ils retrouvent leur efficacit\u00e9 offensive. <strong>\u00a0\u00a0<\/strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>CBPL &#8211; BLAC 2 <\/strong>: En s\u2019inclinant nettement lors de leur d\u00e9placement \u00e0 COTEAUX DU LUY, C.B.P.L a\u00a0 dilapid\u00e9 ses chances de participer \u00e0 la finale. Pour leur derni\u00e8re rencontre \u00e0 domicile, ils seront motiv\u00e9s afin de prendre leur revanche sur B.L.A.C 2 qui l\u2019avait emport\u00e9 lors de la rencontre aller et qui vient de subir la domination de ST CRICQ 2 \u00e0 domicile.\u00a0\u00a0\u00a0\u00a0<strong>\u00a0\u00a0<\/strong>\u00a0\u00a0\u00a0\u00a0<strong>\u00a0<\/strong>\u00a0\u00a0\u00a0\u00a0<strong>\u00a0<\/strong>\u00a0\u00a0<strong>\u00a0\u00a0\u00a0<\/strong>\u00a0\u00a0\u00a0<strong>\u00a0<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>BTO &#8211; US DAX : <\/strong>C\u2019est une rencontre au sommet entre deux \u00e9quipes qui ont acquis un confortable succ\u00e8s\u00a0: B.T.O face \u00e0 A.S.C.H 3, il est vrai handicap\u00e9 par des absences majeures, et l\u2019U.S.DAX dans une rencontre d\u00e9fensive lors de la r\u00e9ception de C.S.A 2. Ce sont aussi les deux favoris pour disputer la finale\u00a0; mais le champion de la saison derni\u00e8re peut venir troubler ce pronostic. B.T.O se voit donc dans l\u2019obligation de prendre sa revanche \u00e0 la suite de son \u00e9chec lors de la rencontre aller. Pour sa part l\u2019U.S.D, en r\u00e9cidivant, assurerait mont\u00e9e et finale\u00a0: beau suspense\u00a0! \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>POULE BASSE \u2013 PLAY-DOWN<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>BARCELONNE &#8211; ARRIGANS 2 : <\/strong>En s\u2019inclinant \u00e0 domicile face \u00e0 A.B.A, BARCELONNE a dilapid\u00e9 en grande partie ses chances de maintien au vu de la conjoncture d\u00e9favorable (4 ou 5 descentes de R3). N\u00e9anmoins il fait partie d\u2019un trio dont il peut s\u2019extirper \u00e0 condition de d\u00e9buter par une victoire face \u00e0 ARRIGANS 2, qui bien qu\u2019ayant pris sa revanche sur ARBOUCAVE, n\u2019a gu\u00e8re aucune chance de se maintenir. <strong>\u00a0<\/strong>\u00a0<strong>\u00a0<\/strong>\u00a0<strong>\u00a0\u00a0<\/strong>\u00a0\u00a0<strong>\u00a0\u00a0<\/strong>\u00a0<strong>\u00a0<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>LABENNE 2 &#8211; ESMS 3 :\u00a0<\/strong>LABENNE 2 a \u00e9t\u00e9 largement domin\u00e9, du moins en premi\u00e8re p\u00e9riode (22\/41) par U.J.S.B.P.2\u00a0 et cette d\u00e9faite le place dans un trio quasiment \u00e9ligible pour la D2. E.S.M.S.3, qui bien que men\u00e9 \u00e0 la pause, a r\u00e9cidiv\u00e9 lors de la r\u00e9ception de VIEUX BOUCAU, est bien plac\u00e9 pour viser la troisi\u00e8me place, esp\u00e9rons le salvatrice. Mais il faudra \u00eatre plus efficace que lors de la rencontre aller o\u00f9 ils avaient \u00e9chou\u00e9.\u00a0 \u00a0\u00a0<strong>\u00a0\u00a0\u00a0<\/strong>\u00a0\u00a0\u00a0\u00a0\u00a0<strong> \u00a0\u00a0<\/strong>\u00a0<strong>\u00a0<\/strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>UJSBP 2 &#8211; VIEUX-BOUCAU :<\/strong>\u00a0U.J.S.B.P.2 a pris une nette revanche face \u00e0 LABENNE 2 et une nouvelle victoire sera synonyme de maintien, ce qui est probable, vu qu\u2019ils avaient vaincu VIEUX BOUCAU \u00e0 l\u2019aller. VIEUX BOUCAU n\u2019a pas tenu la distance lors de sa confrontation avec E.S.M.S.3 perdant l\u2019avantage du point average et voit se rapprocher un d\u00e9nouement peu pr\u00e9visible lors de la premi\u00e8re phase. \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>ARBOUCAVE &#8211; ALBRET BASKET ARMAGNAC :\u00a0<\/strong>En s\u2019imposant \u00e0 BARCELONNE, ayant creus\u00e9 un \u00e9cart suffisant \u00e0 l\u2019issue du troisi\u00e8me quart temps (53\/41), A.B.A\u00a0 a assur\u00e9 son maintien, ce qui est loin d\u2019\u00eatre le cas pour ARBOUCAVE, qui bien que menant \u00e0 la pause a \u00e9chou\u00e9 face \u00e0 ARRIGANS 2. Les locaux essaieront de bien cl\u00f4turer \u00e0 domicile bien qu\u2019A.B.A soit performant lors de ses d\u00e9placements et viennent de cumuler six victoires successives.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>J.L VILLENEUVE\u00a0\u00a0<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>DEPARTEMENTALE 1 FEMININE<\/em><\/strong>&nbsp;<strong><em>\u2013 D1 LAFORET SAINT-SEVER<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>POULE HAUTE \u2013 PLAY-OFF<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>ARBOUCAVE \u2013 ASCH\u00a0: <\/strong>Apr\u00e8s la frustrante d\u00e9faite \u00e0 Labenne, ASCH a su relever la t\u00eate et garder tous ses espoirs de qualification. Faux pas interdit \u00e0 ARBOUCAVE, redoutable dans son antre, et qui n\u2019aura pas fait le poids lors du match aller. Match pi\u00e8ge par excellence, d\u2019autant plus que le calendrier n\u2019est pas cl\u00e9ment pour les horsarroises avec la r\u00e9ception du leader lors de la derni\u00e8re journ\u00e9e, pour ce qui pourrait bien \u00eatre une r\u00e9p\u00e9tition avant la v\u00e9ritable finale du championnat.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>ADB 2 \u2013 COTEAUX DU LUY 2\u00a0: <\/strong>Face \u00e0 un adversaire qui, d\u00e9cid\u00e9ment, ne lui r\u00e9ussit pas, ADB 2 aura montr\u00e9 certaines limites lors de son dernier d\u00e9placement. Soucieuses de se qualifier le plus rapidement possible, il faudra encore un succ\u00e8s pour math\u00e9matiquement verrouiller sa place en finale. COTEAUX DU LUY 2 reste sur une victoire et se d\u00e9placera d\u00e9complex\u00e9, apr\u00e8s avoir bien r\u00e9sist\u00e9 au match aller.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>BLAC 2 \u2013 REAL CHALOSSAIS\u00a0:<\/strong> Le REAL CHALOSSAIS n\u2019est pas maitre de son destin quant \u00e0 la qualification en finale, mais, \u00e0 l\u2019instar de CSGB, en cas de sans faute, pourrait bien rafler la mise, la derni\u00e8re journ\u00e9e offrant un affrontement entre 2 concurrents directs. Pour BLAC, il n\u2019y a gu\u00e8re trop d\u2019enjeu, si ce n\u2019est terminer \u00e0 domicile par une belle performance et un succ\u00e8s face \u00e0 une \u00e9quipe du trio de t\u00eate pour prendre rendez-vous en vue de la saison prochaine.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>LABENNE 2 \u2013 CSGB\u00a0:<\/strong> Pas pass\u00e9es loin de s\u2019imposer en terres chalossaises, les joueuses de LABENNE auraient pu b\u00e9n\u00e9ficier d\u2019un meilleur classement si elles avaient \u00e9t\u00e9 en capacit\u00e9 de valider leurs bonnes prestations en d\u00e9placement. CSGB, avec un bilan de 4\/2 en Play Offs est toujours en course pour la qualification pour la finale, mais pour cela, il faudra r\u00e9aliser le sans faute, face \u00e0 des adversaires qui sont en seconde partie de classement.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>POULE BASSE \u2013 PLAY-DOWN<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>CAMPAGNE MEILHAN \u2013 BBSM\u00a0:<\/strong> Derni\u00e8re lev\u00e9e \u00e0 domicile pour CAMPAGNE MEILHAN. Derni\u00e8re occasion aussi pour essayer de s\u2019imposer et finir sur une bonne note une saison toutefois terne. BBSM a repris les commandes de la poule, en s\u2019imposant face \u00e0 USSAMB et en b\u00e9n\u00e9ficiant du faux pas du Stade Montois. Une belle seconde phase pour les joueuses de X. Lagarde qui n\u2019ont jusqu\u2019alors perdu qu\u2019une seule fois sur cette phase de Play Down.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>STADE MONTOIS 2 \u2013 BOCS\u00a0:<\/strong> Ces 2 \u00e9quipes ont souffert face \u00e0 des \u00e9quipes pourtant mal class\u00e9es le weekend dernier et la premi\u00e8re partie de tableau \u00e9tant acquise, la fin de saison pourrait leur paraitre un peu longue. Le STADE MONTOIS s\u2019est inclin\u00e9 pour la seconde fois dans cette phase, la premi\u00e8re \u00e9tant contre BOCS qu\u2019elles retrouveront ce weekend. Un succ\u00e8s qui leur donnerait droit de jouer une \u00ab\u00a0finale\u00a0\u00bb contre BBSM lors de la derni\u00e8re journ\u00e9e.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>USSAMB 2 \u2013 ARRIGANS 2\u00a0:<\/strong> Lourdement d\u00e9fait en d\u00e9placement, l\u2019USSAMB a laiss\u00e9 passer l\u2019occasion de prendre seul la t\u00eate. Ne b\u00e9n\u00e9ficiant pas du goal average, il faudra imp\u00e9rativement tout gagner pour viser la premi\u00e8re place finale. Les ARRIGANS ont gagn\u00e9 par forfait et seraient inspir\u00e9s de l\u2019emporter pour rester \u00e0 la 5\u00e9me place, leurs adversaires directs se rencontrant et pouvant esp\u00e9rer remonter \u00e0 leur hauteur.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>MORCENX \u2013 ROQUEFORT\u00a0:<\/strong> Confirmation de la bonne p\u00e9riode des joueuses de MORCENX, son dernier succ\u00e8s face \u00e0 une \u00e9quipe qui aurait tr\u00e8s bien pu \u00eatre en Play Offs laisse pr\u00e9sager une belle fin de saison. A voir si cela sera suffisant au ranking, mais les joueuses de MORCENX se donnent le droit d\u2019esp\u00e9rer. Il en est de m\u00eame pour ROQUEFORT qui aura su s\u2019imposer au terme de son long d\u00e9placement \u00e0 BOCS, et ainsi entretenir l\u2019espoir de rester dans le coup jusqu\u2019au bout pour un maintien \u00ab\u00a0\u00e0 la place\u00a0\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>BASTIEN JOURDAN\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>DEPARTEMENTALE MASCULINE 1&nbsp;\u2013 D1 LAFORET SAINT-SEVER POULE HAUTE \u2013 PLAY-OFF ST CRICQ 2 &#8211; COTEAUX DU LUY 3 : ST CRICQ 2 a pris une nette revanche face \u00e0 B.L.A.C [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":3245,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3244","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/www.comite40.lebasket.net\/index.php\/wp-json\/wp\/v2\/posts\/3244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comite40.lebasket.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.comite40.lebasket.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.comite40.lebasket.net\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comite40.lebasket.net\/index.php\/wp-json\/wp\/v2\/comments?post=3244"}],"version-history":[{"count":1,"href":"https:\/\/www.comite40.lebasket.net\/index.php\/wp-json\/wp\/v2\/posts\/3244\/revisions"}],"predecessor-version":[{"id":3246,"href":"https:\/\/www.comite40.lebasket.net\/index.php\/wp-json\/wp\/v2\/posts\/3244\/revisions\/3246"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.comite40.lebasket.net\/index.php\/wp-json\/wp\/v2\/media\/3245"}],"wp:attachment":[{"href":"https:\/\/www.comite40.lebasket.net\/index.php\/wp-json\/wp\/v2\/media?parent=3244"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.comite40.lebasket.net\/index.php\/wp-json\/wp\/v2\/categories?post=3244"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.comite40.lebasket.net\/index.php\/wp-json\/wp\/v2\/tags?post=3244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}